{"id":12123,"date":"2026-08-11T15:22:41","date_gmt":"2026-08-11T13:22:41","guid":{"rendered":"https:\/\/blog.seetal-chile.ch\/?p=12123"},"modified":"2026-08-11T15:24:07","modified_gmt":"2026-08-11T13:24:07","slug":"glow-next-7ab7-3","status":"publish","type":"post","link":"https:\/\/blog.seetal-chile.ch\/fr\/2026\/08\/11\/glow-next-7ab7-3\/","title":{"rendered":"glow Next \u00ab7ab7\u00bb"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>7ab7 est de retour ! Rendez-vous le 6 septembre pour la prochaine \u00e9dition ! Une soir\u00e9e t'attend avec des moments de louange, des partages, de belles discussions et plein de temps pour se retrouver tous ensemble.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 partir de 18 h 30, tu pourras d\u00e9guster un bon d\u00eener dans la salle commune de la maison des jeunes. \u00c0 19 h 07, on commence ensemble par un moment de louange et un partage inspirant. C'est toi qui d\u00e9cides quand tu nous rejoins ! Apr\u00e8s, il y aura plein de temps pour discuter, rigoler, rencontrer des gens et simplement passer un bon moment ensemble.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">glow Next, c'est l'offre de seetal chile destin\u00e9e aux jeunes adultes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors : prends tes potes et passe nous voir \u2013 on t'attend avec impatience !<\/p>","protected":false},"excerpt":{"rendered":"<p>7ab7 est de retour ! Le 6 septembre, c'est reparti pour un nouveau cycle ! Une soir\u00e9e t'attend avec de la louange, des moments de r\u00e9flexion, de belles discussions et plein de temps pour partager ce moment ensemble. \u00c0 partir de 18 h 30, tu pourras d\u00e9guster un bon d\u00eener dans la salle commune de la maison des jeunes. \u00c0 19 h 07, on commencera ensemble par un moment de louange et un temps de r\u00e9flexion inspirant. Toi\u2026<\/p>","protected":false},"author":41,"featured_media":11585,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,8,9],"tags":[],"class_list":["post-12123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-neues","category-vielfalt"],"acf":[],"_links":{"self":[{"href":"https:\/\/blog.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/posts\/12123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/comments?post=12123"}],"version-history":[{"count":3,"href":"https:\/\/blog.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/posts\/12123\/revisions"}],"predecessor-version":[{"id":12126,"href":"https:\/\/blog.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/posts\/12123\/revisions\/12126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/media\/11585"}],"wp:attachment":[{"href":"https:\/\/blog.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/media?parent=12123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/categories?post=12123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/tags?post=12123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}